{"id":136177,"date":"2023-11-08T10:00:00","date_gmt":"2023-11-08T09:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/?p=136177"},"modified":"2023-11-08T16:39:33","modified_gmt":"2023-11-08T15:39:33","slug":"og-kush-tout-ce-quil-faut-savoir-sur-cette-variete","status":"publish","type":"post","link":"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/","title":{"rendered":"OG Kush : tout ce qu&rsquo;il faut savoir sur cette vari\u00e9t\u00e9"},"content":{"rendered":"\n<p><strong>OG Kush.<\/strong> M\u00eame pour les non-initi\u00e9s, les deux initiales les plus connues du monde du cannabis r\u00e9sonnent avec force, tant cette vari\u00e9t\u00e9 a acquis une <strong>renomm\u00e9e \u00e0 l\u2019\u00e9chelle mondiale.<\/strong> Cette r\u00e9putation a depuis longtemps d\u00e9pass\u00e9 les fronti\u00e8res du cannabis, et elle a notamment \u00e9t\u00e9 mise en musique par les plus grands artistes du rap am\u00e9ricain.<\/p>\n\n\n\n<p>Il s\u2019agit pour beaucoup de l\u2019une des souches de cannabis les plus c\u00e9l\u00e8bres de tous les temps. Sa notori\u00e9t\u00e9 est telle qu\u2019elle figure parmi <strong>les plus utilis\u00e9es par les breeders<\/strong> pour r\u00e9aliser des croisements. D\u00e8s sa naissance, elle se vit attribuer le nom de <strong>California Queen,<\/strong> un surnom \u00e9loquent.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a97b94fb6744\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97b94fb6744\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#Histoire_de_lOG_Kush\" >Histoire de l\u2019OG Kush<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#Arome_et_saveur_de_lOG_Kush\" >Ar\u00f4me et saveur de l\u2019OG Kush<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#Effets\" >Effets<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#Culture_de_lOG_Kush\" >Culture de l\u2019OG Kush<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#OG_Kush_CBD\" >OG Kush CBD&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/og-kush-tout-ce-quil-faut-savoir-sur-cette-variete\/#Un_classique_largement_revisite\" >Un classique largement revisit\u00e9<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Histoire_de_lOG_Kush\"><\/span>Histoire de l\u2019OG Kush<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u00c0 l\u2019instar de nombreuses l\u00e9gendes, le <strong>myst\u00e8re entourant ses origines<\/strong> a grandement contribu\u00e9 \u00e0 sa popularit\u00e9. Comme son nom l\u2019indique, sa parent\u00e9 avec les g\u00e9n\u00e9tiques Kush coule de source. Il existe toutefois un certain consensus qui situe ses origines en Floride au d\u00e9but des ann\u00e9es 1990, des \u0153uvres du c\u00e9l\u00e8bre Matt Berger, p\u00e8re de Bubba et de la Kryptonite. Selon une hypoth\u00e8se r\u00e9currente, elle serait le fruit d\u2019un <strong>croisement<\/strong> entre une <strong>Chemdawg<\/strong> et une <strong>Hindu Kush.<\/strong> Par cons\u00e9quent, elle trouve une grande partie de ses racines dans les <strong>montagnes de l\u2019Hindou Kouch,<\/strong> que beaucoup consid\u00e8rent comme l\u2019un des <strong>berceaux historiques<\/strong> du cannabis. <\/p>\n\n\n\n<p>La cr\u00e9ation originale de Matt Berger voyagea ensuite jusqu\u2019en Californie, o\u00f9 le fameux <strong>Josh D<\/strong> r\u00e9cup\u00e9ra une bouture de Matt Berger et fa\u00e7onna d\u00e9finitivement l\u2019<a href=\"https:\/\/www.gbthegreenbrand.fr\/graines-en-vrac\/3388-og-kush-100-feminisee.html\">OG Kush<\/a> telle qu\u2019on la conna\u00eet aujourd\u2019hui. Ces origines incertaines et ces l\u00e9gendes urbaines entretiennent le flou artistique qui r\u00e8gne au sujet de cette vari\u00e9t\u00e9. C\u2019est pourquoi <strong>sa teneur en THC et son profil terp\u00e9nique varient <\/strong>parfois d\u2019une banque de graines \u00e0 l\u2019autre. Toutefois, on peut toutefois d\u00e9gager des traits communs qui ne tromperont aucun amateur de cannabis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Arome_et_saveur_de_lOG_Kush\"><\/span>Ar\u00f4me et saveur de l\u2019OG Kush<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-weed.jpg\" alt=\"weed OG Kush\" class=\"wp-image-136193\" srcset=\"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-weed.jpg 1000w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-weed-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-weed-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p>Indubitablement, ce qui caract\u00e9rise la saveur d\u2019OG Kush, c\u2019est qu\u2019elle est <strong>reconnaissable entre toutes.<\/strong> Les connaisseurs d\u00e9tecteront sa fum\u00e9e incomparable d\u00e8s les premi\u00e8res bouff\u00e9es. Elle poss\u00e8de une saveur r\u00e9ellement unique en son genre, associant des <strong>touches d\u2019agrumes<\/strong> \u00e0 des <strong>notes terreuses, de pin et d\u2019essence.<\/strong> Le tout donne un ressenti en bouche constituant un v\u00e9ritable d\u00e9lice pour le palais. L\u2019OG Kush a conquis de nombreux puristes du cannabis et continuera \u00e0 s\u00e9vir durant de nombreuses g\u00e9n\u00e9rations encore. Elle doit ce bouquet particulier et enivrant \u00e0 la pr\u00e9sence majoritaire de <a href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quest-ce-que-le-b-caryophyllene\/\">caryophyll\u00e8ne<\/a>, de myrc\u00e8ne et de limon\u00e8ne au sein de son profil terp\u00e9nique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Effets\"><\/span>Effets<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Si la saveur exceptionnelle de l\u2019OG Kush a jou\u00e9 un r\u00f4le important dans sa notori\u00e9t\u00e9, ses <strong>vertus relaxantes et m\u00e9dicinales<\/strong> lui ont \u00e9galement permis d\u2019acqu\u00e9rir ses lettres de noblesse. Le succ\u00e8s rencontr\u00e9 par l\u2019OG Kush r\u00e9side dans ses <strong>effets remarquablement \u00e9quilibr\u00e9s,<\/strong> malgr\u00e9 sa <strong>dominante de pure indica<\/strong> afghane, \u00e0 raison de 75-80 %. C\u2019est sur ce point qu\u2019elle se distingue des souches Kush originales. Sa teneur en <strong>THC<\/strong> se situe g\u00e9n\u00e9ralement dans une fourchette comprise <strong>entre 20 et 26 %,<\/strong> donnant \u00e0 ses fleurs une puissance exceptionnelle. Elle engendre des effets corporels se manifestant par un <strong>sentiment de d\u00e9tente<\/strong> digne des meilleures indica. Toutefois, cette sensation de relax est souvent associ\u00e9e \u00e0 un <strong>high mental<\/strong> offrant une sensation de bien-\u00eatre et de l\u00e9g\u00e8ret\u00e9, facilitant le rapport \u00e0 l&rsquo;autre et provoquant d\u2019interminables parties de fous rires.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-joint.jpg\" alt=\"Joint OG Kush\" class=\"wp-image-136188\" srcset=\"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-joint.jpg 1000w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-joint-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2023\/11\/OG-Kush-joint-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p>Gr\u00e2ce \u00e0 ce cocktail unique, elle fait des miracles dans la <strong>lutte contre la d\u00e9pression<\/strong> ou contre les troubles de l\u2019humeur. En outre, on a constat\u00e9 sa facult\u00e9 \u00e0 soulager la <strong>douleur chronique, la migraine et la naus\u00e9e,<\/strong> mais aussi \u00e0 combattre les <strong>troubles de l\u2019app\u00e9tit ou de l\u2019estomac,<\/strong> touchant un large \u00e9ventail de patients.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Culture_de_lOG_Kush\"><\/span>Culture de l\u2019OG Kush<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Comme \u00e9voqu\u00e9 pr\u00e9c\u00e9demment, l&rsquo;OG Kush doit son succ\u00e8s \u00e0 ses effets tol\u00e9rables par le plus grand nombre. Il en va de m\u00eame pour sa culture qui ne pr\u00e9sente aucun obstacle majeur et qui offre un <strong>excellent rendement,<\/strong> m\u00eame pour les non-initi\u00e9s. Un rappel historique s\u2019impose ici, afin de bien comprendre les raisons pour lesquelles l\u2019OG Kush est devenue l\u2019une des g\u00e9n\u00e9tiques que l\u2019on retrouve le plus souvent dans les salles et chambres de culture. Son histoire est intimement li\u00e9e \u00e0 l\u2019explosion de la culture en int\u00e9rieur, faisant suite \u00e0 la prohibition du cannabis aux \u00c9tats-Unis. <\/p>\n\n\n\n<p>En effet, <strong>simple \u00e0 cultiver en indoor,<\/strong> elle offre une r\u00e9colte pouvant <strong>d\u00e9passer le demi-kilo par m<sup>2<\/sup>,<\/strong> notamment en hydroponie. En ext\u00e9rieur, la production se situe g\u00e9n\u00e9ralement aux alentours de <strong>550 g par pied,<\/strong> mais certains n\u2019h\u00e9sitent pas \u00e0 affirmer que la r\u00e9colte peut d\u00e9passer le kilo en climat chaud, des chiffres ahurissants qui la placent parmi les souches les plus productives. Comme toutes les Kush, elle se recouvre d\u2019une <strong>r\u00e9sine abondante,<\/strong> pour le plus grand plaisir des amateurs de concentr\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"OG_Kush_CBD\"><\/span>OG Kush CBD&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La saveur exquise de l\u2019OG Kush a fait d\u2019elle l\u2019une des <strong>vari\u00e9t\u00e9s favorites des breeders <\/strong>cherchant \u00e0 cr\u00e9er des <strong>souches de cannabis m\u00e9dical.<\/strong> Les boutiques de CBD leur ont embo\u00eet\u00e9 le pas en mettant sur le march\u00e9 cette vari\u00e9t\u00e9 de cannabis m\u00e9dical dont la saveur saura <strong>conqu\u00e9rir de nombreux palais<\/strong> non avertis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Un_classique_largement_revisite\"><\/span>Un classique largement revisit\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>L\u2019OG Kush a acquis une telle r\u00e9putation qu\u2019elle a \u00e9t\u00e9 d\u00e9clin\u00e9e sous de nombreuses formes, engendrant une <strong>infinit\u00e9 d\u2019hybrides et descendants.<\/strong> Il existe aujourd\u2019hui une multitude de versions de l&rsquo;OG Kush, mais les <strong>banques de graines<\/strong> ont surf\u00e9 sur la vague de succ\u00e8s de cette souche en y apportant des <strong>touches sp\u00e9ciales,<\/strong> de sorte que certaines h\u00e9riti\u00e8res de l\u2019OG Kush sont bien \u00e9loign\u00e9es de l\u2019originale.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>L\u2019OG Kush est l\u2019une des souches de cannabis les plus connues. Mais que se cache-t-il r\u00e9ellement derri\u00e8re ces deux initiales ?<\/p>\n","protected":false},"author":18,"featured_media":136183,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[225],"tags":[],"class_list":{"0":"post-136177","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites-sur-le-cannabis"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":6,"sum_votes":28},"_links":{"self":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/136177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/comments?post=136177"}],"version-history":[{"count":2,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/136177\/revisions"}],"predecessor-version":[{"id":136210,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/136177\/revisions\/136210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media\/136183"}],"wp:attachment":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media?parent=136177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/categories?post=136177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/tags?post=136177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}