{"id":203412,"date":"2025-05-15T10:00:00","date_gmt":"2025-05-15T08:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/?p=203412"},"modified":"2025-11-06T16:40:01","modified_gmt":"2025-11-06T15:40:01","slug":"effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces","status":"publish","type":"post","link":"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/","title":{"rendered":"Effet du chlore sur les plantes : avantages et risques d\u2019exc\u00e8s"},"content":{"rendered":"\n<p>Le chlore est un \u00e9l\u00e9ment essentiel pour la croissance des plantes, mais en exc\u00e8s, il peut devenir un ennemi silencieux. D\u00e9couvrez comment <strong>identifier l&rsquo;effet du chlore sur les plantes en cas d&rsquo;application excessive,<\/strong> ainsi que les solutions pratiques pour le corriger et le pr\u00e9venir. Nous vous donnerons \u00e9galement des conseils sur la fa\u00e7on de choisir l&rsquo;eau d&rsquo;arrosage appropri\u00e9e et de maintenir une culture saine et durable.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a989a0fe7bdd\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a989a0fe7bdd\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Quest-ce_que_le_chlore_et_pourquoi_est-il_important_pour_les_plantes\" >Qu&rsquo;est-ce que le chlore et pourquoi est-il important pour les plantes ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Le_chlore_dans_la_nature\" >Le chlore dans la nature<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Fonctions_du_chlore_dans_les_plantes\" >Fonctions du chlore dans les plantes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Quelle_quantite_de_chlore_les_plantes_necessitent-elles\" >Quelle quantit\u00e9 de chlore les plantes n\u00e9cessitent-elles ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Comment_se_produit_lexces_de_chlore_chez_les_plantes\" >Comment se produit l&rsquo;exc\u00e8s de chlore chez les plantes ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Eau_darrosage_a_haute_teneur_en_chlore\" >Eau d&rsquo;arrosage \u00e0 haute teneur en chlore<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Utilisation_excessive_dengrais_contenant_des_chlorures\" >Utilisation excessive d&rsquo;engrais contenant des chlorures<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Substrats_de_mauvaise_qualite_ou_mal_draines\" >Substrats de mauvaise qualit\u00e9 ou mal drain\u00e9s<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Symptomes_de_lexces_de_chlore_chez_les_plantes\" >Sympt\u00f4mes de l&rsquo;exc\u00e8s de chlore chez les plantes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Dommages_aux_feuilles_causes_par_un_exces_de_chlore\" >Dommages aux feuilles caus\u00e9s par un exc\u00e8s de chlore<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Effets_sur_la_croissance_et_le_rendement\" >Effets sur la croissance et le rendement<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Comment_differencier_un_exces_de_chlore_dautres_problemes\" >Comment diff\u00e9rencier un exc\u00e8s de chlore d&rsquo;autres probl\u00e8mes ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Comment_mesurer_les_niveaux_de_chlore\" >Comment mesurer les niveaux de chlore&nbsp;?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Mesurer_le_chlore_dans_leau\" >Mesurer le chlore dans l&rsquo;eau<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Mesurer_le_chlore_dans_le_substrat\" >Mesurer le chlore dans le substrat<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Comment_interpreter_les_resultats\" >Comment interpr\u00e9ter les r\u00e9sultats<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Mesurer_dautres_valeurs\" >Mesurer d&rsquo;autres valeurs<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Que_faire_si_vous_detectez_des_niveaux_eleves_de_chlore\" >Que faire si vous d\u00e9tectez des niveaux \u00e9lev\u00e9s de chlore ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Rincage_des_racines\" >Rin\u00e7age des racines<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Remplacez_le_substrat\" >Remplacez le substrat<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Remplacez_leau_darrosage\" >Remplacez l&rsquo;eau d&rsquo;arrosage<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Ajustez_le_pH_et_lEC_du_substrat\" >Ajustez le pH et l&rsquo;EC du substrat<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Renforcez_les_plantes_apres_le_stress_cause_par_le_chlore\" >Renforcez les plantes apr\u00e8s le stress caus\u00e9 par le chlore<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#FAQ_sur_lexces_de_chlore_dans_les_plantes\" >FAQ sur l&rsquo;exc\u00e8s de chlore dans les plantes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Comment_savoir_si_ma_plante_a_un_exces_de_chlore\" >Comment savoir si ma plante a un exc\u00e8s de chlore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Leau_du_robinet_peut-elle_provoquer_un_exces_de_chlore_dans_les_plantes\" >L&rsquo;eau du robinet peut-elle provoquer un exc\u00e8s de chlore dans les plantes ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Que_faire_si_ma_plante_a_deja_un_exces_de_chlore\" >Que faire si ma plante a d\u00e9j\u00e0 un exc\u00e8s de chlore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/#Un_exces_de_chlore_peut-il_tuer_une_plante\" >Un exc\u00e8s de chlore peut-il tuer une plante ?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quest-ce_que_le_chlore_et_pourquoi_est-il_important_pour_les_plantes\"><\/span>Qu&rsquo;est-ce que le chlore et pourquoi est-il important pour les plantes ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Le chlore (Cl) est un \u00e9l\u00e9ment chimique souvent associ\u00e9 \u00e0 la d\u00e9sinfection de l&rsquo;eau, mais il joue \u00e9galement <strong>un r\u00f4le crucial dans le d\u00e9veloppement des plantes.<\/strong> C&rsquo;est l&rsquo;un des micronutriments essentiels dont les plantes ont besoin en petites quantit\u00e9s pour accomplir des fonctions vitales. Bien que leurs besoins soient minimes, une absence ou un exc\u00e8s de chlore peut avoir des effets s\u00e9rieux sur la sant\u00e9 et la croissance des cultures.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Le_chlore_dans_la_nature\"><\/span>Le chlore dans la nature<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le chlore se trouve <strong>naturellement dans le sol, l&rsquo;eau et l&rsquo;atmosph\u00e8re.<\/strong> Dans le sol, il est pr\u00e9sent sous forme de chlorures, des compos\u00e9s ioniques solubles dans l&rsquo;eau. Les plantes assimilent le chlore principalement par les racines, mais elles peuvent aussi en absorber de petites quantit\u00e9s par les feuilles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Fonctions_du_chlore_dans_les_plantes\"><\/span>Fonctions du chlore dans les plantes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le chlore participe \u00e0 plusieurs processus physiologiques cl\u00e9s qui sont essentiels pour la croissance et le d\u00e9veloppement des plantes. Voici ses fonctions les plus importantes&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Photosynth\u00e8se.<\/strong> Le chlore est essentiel \u00e0 la photosynth\u00e8se, le processus par lequel les plantes convertissent l&rsquo;\u00e9nergie lumineuse en \u00e9nergie chimique.<\/li>\n\n\n\n<li><strong>R\u00e9gulation des stomates.<\/strong> Les stomates sont de petites ouvertures sur les feuilles qui permettent les \u00e9changes gazeux, comme l&rsquo;entr\u00e9e de dioxyde de carbone (CO\u2082) et la sortie d&rsquo;oxyg\u00e8ne (O\u2082). Le chlore aide \u00e0 r\u00e9guler l&rsquo;ouverture et la fermeture de ces stomates.<\/li>\n\n\n\n<li><strong>\u00c9quilibre ionique et osmotique.<\/strong> Le chlore agit comme ion r\u00e9gulateur \u00e0 l&rsquo;int\u00e9rieur des cellules v\u00e9g\u00e9tales. Il aide \u00e0 maintenir l&rsquo;\u00e9quilibre osmotique, c&rsquo;est-\u00e0-dire la pression n\u00e9cessaire pour que les cellules restent turgescentes et fonctionnelles.<\/li>\n\n\n\n<li><strong>R\u00e9sistance aux maladies.<\/strong> Des \u00e9tudes ont montr\u00e9 que le chlore peut renforcer la r\u00e9sistance des plantes aux maladies caus\u00e9es par des champignons et des bact\u00e9ries.<\/li>\n\n\n\n<li><strong>Activation enzymatique.<\/strong> Le chlore est un cofacteur essentiel pour certaines enzymes, comme l&rsquo;anhydrase carbonique, qui intervient dans la fixation du CO\u2082 pendant la photosynth\u00e8se. Sans chlore, ces enzymes ne peuvent pas fonctionner correctement.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelle_quantite_de_chlore_les_plantes_necessitent-elles\"><\/span>Quelle quantit\u00e9 de chlore les plantes n\u00e9cessitent-elles ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Bien que le chlore soit essentiel, les plantes en ont besoin en tr\u00e8s petites quantit\u00e9s, g\u00e9n\u00e9ralement <strong>entre 0,2 et 0,4 mg par gramme de mati\u00e8re s\u00e8che.<\/strong> La plupart des sols et des sources d&rsquo;eau contiennent suffisamment de chlore pour r\u00e9pondre \u00e0 ces besoins, il est donc rarement n\u00e9cessaire de l&rsquo;ajouter sous forme d&rsquo;engrais.<\/p>\n\n\n\n<p>Le chlore est un parfait exemple de l&rsquo;adage <strong>\u00ab\u00a0l&rsquo;exc\u00e8s nuit en tout\u00a0\u00bb<\/strong> en mati\u00e8re de nutrition v\u00e9g\u00e9tale. Alors qu&rsquo;une quantit\u00e9 ad\u00e9quate de chlore est b\u00e9n\u00e9fique pour les plantes, un exc\u00e8s peut \u00eatre toxique et entra\u00eener des probl\u00e8mes comme des br\u00fblures sur les feuilles, une inhibition de la croissance et des dommages aux racines. C&rsquo;est pourquoi il est crucial de savoir comment g\u00e9rer les niveaux de chlore dans l&rsquo;eau d&rsquo;arrosage et le <strong>substrat<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-de-cloro.jpg\" alt=\"Effet de chlore sur les plantes de cannabis\" class=\"wp-image-199928\" srcset=\"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-de-cloro.jpg 1000w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-de-cloro-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-de-cloro-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_se_produit_lexces_de_chlore_chez_les_plantes\"><\/span>Comment se produit l&rsquo;exc\u00e8s de chlore chez les plantes ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>L&rsquo;exc\u00e8s de chlore chez les plantes peut r\u00e9sulter de plusieurs facteurs, dont beaucoup sont li\u00e9s aux pratiques courantes de culture et d&rsquo;arrosage. Bien que le chlore soit un micronutriment essentiel, son accumulation dans le substrat ou les tissus v\u00e9g\u00e9taux <strong>peut devenir toxique et nuire \u00e0 la croissance des plantes.<\/strong> Voici les principales sources et causes d&rsquo;un exc\u00e8s de chlore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eau_darrosage_a_haute_teneur_en_chlore\"><\/span>Eau d&rsquo;arrosage \u00e0 haute teneur en chlore<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Une des sources les plus courantes d&rsquo;exc\u00e8s de chlore chez les plantes est l&rsquo;eau d&rsquo;arrosage. De nombreuses <strong>sources d&rsquo;eau potable<\/strong>, en particulier dans les zones urbaines, contiennent du <strong>chlore ajout\u00e9 dans le cadre du processus de d\u00e9sinfection.<\/strong> Bien que ce chlore soit sans danger pour la consommation humaine, il peut \u00eatre nuisible pour les plantes s&rsquo;il n&rsquo;est pas correctement g\u00e9r\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Utilisation_excessive_dengrais_contenant_des_chlorures\"><\/span>Utilisation excessive d&rsquo;engrais contenant des chlorures<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Certains <strong>engrais contiennent des chlorures<\/strong> comme composant principal. Bien que ces engrais puissent \u00eatre utiles dans certains contextes, leur utilisation excessive ou inappropri\u00e9e peut entra\u00eener une accumulation de chlore dans le substrat. Voici quelques exemples d&rsquo;engrais courants contenant des chlorures :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chlorure de potassium (KCl).<\/strong> Largement utilis\u00e9 comme source de potassium.<\/li>\n\n\n\n<li><strong>Chlorure de calcium (CaCl\u2082).<\/strong> Parfois utilis\u00e9 pour corriger les carences en calcium.<\/li>\n\n\n\n<li><strong>Chlorure d&rsquo;ammonium (NH\u2084Cl).<\/strong> Engrais azot\u00e9 qui apporte \u00e9galement du chlore.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Substrats_de_mauvaise_qualite_ou_mal_draines\"><\/span>Substrats de mauvaise qualit\u00e9 ou mal drain\u00e9s<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le type de substrat utilis\u00e9 peut \u00e9galement influencer l&rsquo;accumulation de chlore. Les substrats de mauvaise qualit\u00e9 ou avec un <strong>drainage insuffisant<\/strong> ont tendance \u00e0 retenir les sels, y compris les chlorures, ce qui augmente le risque de toxicit\u00e9. De plus, les terreaux compact\u00e9s emp\u00eachent le flux d&rsquo;eau et favorisent l&rsquo;accumulation de sels.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Symptomes_de_lexces_de_chlore_chez_les_plantes\"><\/span>Sympt\u00f4mes de l&rsquo;exc\u00e8s de chlore chez les plantes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>L&rsquo;exc\u00e8s de chlore sur les plantes peut se manifester de diff\u00e9rentes mani\u00e8res, \u00e0 la fois dans l&rsquo;apparence et dans le d\u00e9veloppement global des plantes. Identifier ces sympt\u00f4mes rapidement est essentiel pour prendre des <strong>mesures correctives<\/strong> et \u00e9viter des dommages irr\u00e9versibles.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-cloro-2.jpg\" alt=\"exc\u00e8s de chlore sur les plantes\" class=\"wp-image-199940\" srcset=\"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-cloro-2.jpg 1000w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-cloro-2-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-exceso-cloro-2-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dommages_aux_feuilles_causes_par_un_exces_de_chlore\"><\/span>Dommages aux feuilles caus\u00e9s par un exc\u00e8s de chlore<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les sympt\u00f4mes visuels sont souvent les premiers signes indiquant un probl\u00e8me de chlore. Voici comment les reconna\u00eetre.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Br\u00fblures sur les feuilles.<\/strong> Les pointes et les bords des feuilles deviennent bruns ou jaun\u00e2tres, comme s&rsquo;ils \u00e9taient br\u00fbl\u00e9s. Initialement, les br\u00fblures apparaissent sur les feuilles les plus anciennes, mais peuvent \u00e9galement affecter les feuilles plus jeunes si le probl\u00e8me persiste.<\/li>\n\n\n\n<li><strong>Chlorose.<\/strong> Les feuilles deviennent moins verdoyantes et plus jaun\u00e2tres. Contrairement \u00e0 la chlorose caus\u00e9e par des carences nutritionnelles, celle due \u00e0 un exc\u00e8s de chlore appara\u00eet g\u00e9n\u00e9ralement d&rsquo;abord sur les feuilles les plus anciennes.<\/li>\n\n\n\n<li><strong>N\u00e9crose foliaire.<\/strong> Des taches brunes ou noires apparaissent sur les feuilles, qui finissent par se dess\u00e9cher et mourir. Les zones n\u00e9crotiques peuvent s&rsquo;\u00e9tendre et entra\u00eener une chute pr\u00e9matur\u00e9e des feuilles.<\/li>\n\n\n\n<li><strong>Fl\u00e9trissement.<\/strong> Les feuilles paraissent tombantes et molles, m\u00eame lorsque le substrat est humide. L&rsquo;exc\u00e8s de chlore endommage les racines et r\u00e9duit leur capacit\u00e9 \u00e0 absorber l&rsquo;eau et les nutriments.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Effets_sur_la_croissance_et_le_rendement\"><\/span>Effets sur la croissance et le rendement<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En plus des sympt\u00f4mes visibles, <strong>l&rsquo;exc\u00e8s de chlore<\/strong> peut avoir un impact profond sur la croissance et le rendement des plantes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Croissance ralentie.<\/strong> Les plantes montrent un d\u00e9veloppement lent ou in\u00e9gal, avec des tiges courtes et des petites feuilles.<\/li>\n\n\n\n<li><strong>Dommages aux racines.<\/strong> Les racines deviennent plus courtes, plus \u00e9paisses et de couleur fonc\u00e9e. Dans les cas graves, des l\u00e9sions ou des pourritures peuvent appara\u00eetre.<\/li>\n\n\n\n<li><strong>R\u00e9duction de la photosynth\u00e8se.<\/strong> L&rsquo;exc\u00e8s de chlore interf\u00e8re avec la photosynth\u00e8se en endommageant les chloroplastes, les structures cellulaires responsables de ce processus. La plante produit moins d&rsquo;\u00e9nergie, ce qui entra\u00eene une croissance plus lente et une production r\u00e9duite de fleurs et de fruits.<\/li>\n\n\n\n<li><strong>D\u00e9s\u00e9quilibre nutritionnel.<\/strong> Un exc\u00e8s de chlore peut entrer en comp\u00e9tition avec d&rsquo;autres nutriments, comme l&rsquo;azote et le potassium, et en r\u00e9duire l&rsquo;absorption. Cela peut entra\u00eener des carences secondaires qui aggravent les probl\u00e8mes de la plante.<\/li>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_differencier_un_exces_de_chlore_dautres_problemes\"><\/span>Comment diff\u00e9rencier un exc\u00e8s de chlore d&rsquo;autres probl\u00e8mes ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les sympt\u00f4mes d&rsquo;un exc\u00e8s de chlore peuvent facilement \u00eatre <strong>confondus avec ceux d&rsquo;autres carences<\/strong> ou toxicit\u00e9s. Voici quelques \u00e9l\u00e9ments pour les diff\u00e9rencier :<\/p>\n\n\n\n<figure class=\"wp-block-table\">\n  <table style=\"width:100%; border-collapse: collapse; font-family: Arial, sans-serif;\">\n    <thead>\n      <tr style=\"background-color: #e6e6e6;\">\n        <th style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Sympt\u00f4me<\/th>\n        <th style=\"border: 1px solid #ccc; padding: 10px;\">Exc\u00e8s de Chlore<\/th>\n        <th style=\"border: 1px solid #ccc; padding: 10px;\">Carence en Azote<\/th>\n        <th style=\"border: 1px solid #ccc; padding: 10px;\">Toxicit\u00e9 du Sodium<\/th>\n        <th style=\"border: 1px solid #ccc; padding: 10px;\">Stress Hydrique<\/th>\n      <\/tr>\n    <\/thead>\n    <tbody>\n      <tr>\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Br\u00fblures des feuilles<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Extr\u00e9mit\u00e9s et bords des feuilles bruns ou jaun\u00e2tres, surtout sur les feuilles les plus anciennes.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Pas de br\u00fblures ; feuilles enti\u00e8rement jaunes.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Br\u00fblures g\u00e9n\u00e9ralis\u00e9es sur toute la feuille ; les feuilles peuvent s&rsquo;enrouler.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Pas de br\u00fblures ; les feuilles se fl\u00e9trissent et se dess\u00e8chent.<\/td>\n      <\/tr>\n      <tr style=\"background-color: #f9f9f9;\">\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Chlorose<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Jaunissement des feuilles les plus anciennes, commen\u00e7ant par les bords et progressant vers le centre.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Jaunissement uniforme des feuilles les plus anciennes, sans br\u00fblures.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Jaunissement irr\u00e9gulier, souvent accompagn\u00e9 de br\u00fblures.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">L\u00e9ger jaunissement, g\u00e9n\u00e9ralement sur les feuilles plus jeunes.<\/td>\n      <\/tr>\n      <tr>\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Fl\u00e9trissement<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Feuilles tombantes m\u00eame lorsque le substrat est humide.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Feuilles tombantes, associ\u00e9es \u00e0 une croissance lente.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Feuilles tombantes et enroul\u00e9es, aspect br\u00fbl\u00e9.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Feuilles tombantes uniquement lorsque le substrat est sec.<\/td>\n      <\/tr>\n      <tr style=\"background-color: #f9f9f9;\">\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Croissance ralentie<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Croissance lente, tiges courtes et feuilles petites.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Croissance lente, feuilles petites et jaunes.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Croissance tr\u00e8s lente, avec feuilles \u00e9paisses et br\u00fbl\u00e9es.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Croissance lente, feuilles s\u00e8ches et cassantes.<\/td>\n      <\/tr>\n      <tr>\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Racines<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Racines courtes, \u00e9paisses et sombres ; peuvent pr\u00e9senter des l\u00e9sions.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Racines normales, mais absorption limit\u00e9e de l&rsquo;azote.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Racines affect\u00e9es par l&rsquo;accumulation de sels.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Racines s\u00e8ches et cassantes en raison du manque d&rsquo;eau.<\/td>\n      <\/tr>\n      <tr style=\"background-color: #f9f9f9;\">\n        <td style=\"border: 1px solid #ccc; padding: 10px; background-color: #dcdcdc; white-space: nowrap;\">Autres sympt\u00f4mes<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">N\u00e9crose sur les extr\u00e9mit\u00e9s des feuilles et chute pr\u00e9matur\u00e9e des feuilles.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Chute pr\u00e9matur\u00e9e des feuilles les plus anciennes ; croissance faible.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Accumulation de sels visibles \u00e0 la surface du substrat.<\/td>\n        <td style=\"border: 1px solid #ccc; padding: 10px;\">Substrat sec et craquel\u00e9 ; feuilles cassantes.<\/td>\n      <\/tr>\n    <\/tbody>\n  <\/table>\n<\/figure>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_mesurer_les_niveaux_de_chlore\"><\/span>Comment mesurer les niveaux de chlore&nbsp;?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Mesurer les niveaux de chlore dans l&rsquo;eau d&rsquo;arrosage et le substrat est une \u00e9tape essentielle pour <strong>pr\u00e9venir et corriger les probl\u00e8mes de toxicit\u00e9<\/strong> chez les plantes. Heureusement, il existe des outils et des m\u00e9thodes accessibles pour \u00e9valuer la concentration de chlore avec pr\u00e9cision.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mesurer_le_chlore_dans_leau\"><\/span>Mesurer le chlore dans l&rsquo;eau<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>L&rsquo;eau d&rsquo;arrosage est l&rsquo;une des <strong>principales sources de chlore<\/strong>, il est donc crucial d&rsquo;en \u00e9valuer la concentration avant de l&rsquo;utiliser. Voici quelques m\u00e9thodes courantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Bandes r\u00e9actives.<\/strong> Faciles \u00e0 utiliser et rapides, il suffit de plonger la bande dans l&rsquo;eau et de comparer la couleur obtenue avec l&rsquo;\u00e9chelle fournie.<\/li>\n\n\n\n<li><strong>Tests par gouttes.<\/strong> Ils consistent \u00e0 ajouter quelques gouttes de r\u00e9actif \u00e0 un \u00e9chantillon d&rsquo;eau. Le changement de couleur indique le niveau de chlore pr\u00e9sent.<\/li>\n\n\n\n<li><strong>Testeur num\u00e9rique de chlore.<\/strong> C&rsquo;est une option plus pr\u00e9cise et professionnelle, id\u00e9ale si un contr\u00f4le strict est n\u00e9cessaire.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mesurer_le_chlore_dans_le_substrat\"><\/span>Mesurer le chlore dans le substrat<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Comme nous l&rsquo;avons vu, le chlore peut \u00e9galement s&rsquo;accumuler dans le substrat, en particulier si vous utilisez de l&rsquo;eau chlor\u00e9e ou des engrais contenant des chlorures. Il est donc important de mesurer la concentration pour d\u00e9terminer si un changement de substrat est n\u00e9cessaire.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lixiviation.<\/strong> Pour mesurer le chlore dans le substrat, vous pouvez effectuer une lixiviation. Cela consiste \u00e0 arroser le substrat avec de l&rsquo;eau distill\u00e9e, recueillir l&rsquo;eau drain\u00e9e et mesurer la concentration de chlore \u00e0 l&rsquo;aide de l&rsquo;une des m\u00e9thodes mentionn\u00e9es ci-dessus. Cette m\u00e9thode est utile, car le chlore dans le substrat se lib\u00e8re dans l&rsquo;eau.<\/li>\n\n\n\n<li><strong>Testeurs de chlore pour substrats.<\/strong> Il existe des testeurs sp\u00e9cifiques pour substrats, mais ils sont g\u00e9n\u00e9ralement moins courants que ceux con\u00e7us pour l&rsquo;eau.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-GB-1000-18-1.jpg\" alt=\"exc\u00e8s de chlore sur les plantes de cannabis\" class=\"wp-image-199976\" srcset=\"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-GB-1000-18-1.jpg 1000w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-GB-1000-18-1-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.fr\/blog\/wp-content\/uploads\/2025\/03\/Imagen-interior-GB-1000-18-1-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_interpreter_les_resultats\"><\/span>Comment interpr\u00e9ter les r\u00e9sultats<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En g\u00e9n\u00e9ral, les outils et kits de mesure du chlore incluent des instructions pour interpr\u00e9ter les r\u00e9sultats. Voici des niveaux approximatifs :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Mesure du Chlore<\/th><th>Niveau S\u00fbr<\/th><th>Niveau Pr\u00e9occupant<\/th><th>Niveau Toxique<\/th><\/tr><\/thead><tbody><tr><td>Eau<\/td><td>Moins de 0,5 ppm de chlorures<\/td><td>Entre 0,5 et 2 ppm<\/td><td>Plus de 2 ppm<\/td><\/tr><tr><td>Substrat<\/td><td>Moins de 50 ppm de chlorures<\/td><td>Entre 50 et 200 ppm<\/td><td>Plus de 200 ppm<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mesurer_dautres_valeurs\"><\/span>Mesurer d&rsquo;autres valeurs<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>L&rsquo;exc\u00e8s de chlore peut affecter \u00e0 la fois <strong>le pH et l&rsquo;EC (conductivit\u00e9 \u00e9lectrique) de l&rsquo;eau et du substrat<\/strong>, bien que cela ne soit pas toujours \u00e9vident. Le chlore sous forme d&rsquo;hypochlorite de sodium (comme dans l&rsquo;eau du robinet) a tendance \u00e0 augmenter le pH, le rendant plus alcalin. Cependant, s&rsquo;il r\u00e9agit avec d&rsquo;autres compos\u00e9s pr\u00e9sents dans le sol, il peut former des acides et abaisser le pH.<\/p>\n\n\n\n<p>En exc\u00e8s, le chlore augmente \u00e9galement la conductivit\u00e9 \u00e9lectrique (EC) en ajoutant des sels solubles \u00e0 l&rsquo;eau et au substrat, ce qui peut <strong>compliquer l&rsquo;absorption des autres nutriments essentiels.<\/strong> Alors, est-il possible de d\u00e9tecter un exc\u00e8s de chlore uniquement en mesurant le pH, l&rsquo;EC et en observant les sympt\u00f4mes ? Oui, mais avec certaines limitations. Si vous constatez que le pH devient instable (plus \u00e9lev\u00e9 ou impr\u00e9visible) et que l&rsquo;EC augmente sans ajout d&rsquo;engrais, cela peut indiquer une accumulation de chlore ou de chlorures dans le substrat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_faire_si_vous_detectez_des_niveaux_eleves_de_chlore\"><\/span>Que faire si vous d\u00e9tectez des niveaux \u00e9lev\u00e9s de chlore ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Si vous d\u00e9tectez des niveaux \u00e9lev\u00e9s de chlore dans l&rsquo;eau ou le substrat, il est important d&rsquo;<strong>agir rapidement pour \u00e9viter des dommages aux plantes.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rincage_des_racines\"><\/span>Rin\u00e7age des racines<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le lavage des racines est une technique efficace pour \u00e9liminer l&rsquo;exc\u00e8s de sels, y compris les chlorures, du substrat. Voici comment proc\u00e9der :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9parez de l&rsquo;eau propre. Utilisez de l&rsquo;<strong>eau filtr\u00e9e, de pluie ou repos\u00e9e (sans chlore).<\/strong><\/li>\n\n\n\n<li><strong>Arrosez abondamment.<\/strong> Appliquez l&rsquo;eau lentement sur le substrat jusqu&rsquo;\u00e0 ce qu&rsquo;elle s&rsquo;\u00e9coule par les trous de drainage.<\/li>\n\n\n\n<li>De fa\u00e7on optionnelle, vous pouvez ajouter des produits sp\u00e9ciaux pour le <strong><a href=\"https:\/\/www.gbthegreenbrand.fr\/engrais-advanced-hydroponics\/1664-final-solution.html\">rin\u00e7age des racines<\/a><\/strong>, qui facilitent un nettoyage plus en profondeur.<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez le processus. Effectuez cette op\u00e9ration <strong>2 \u00e0 3 fois<\/strong> pour vous assurer que les sels sont bien \u00e9limin\u00e9s.<\/li>\n\n\n\n<li>\u00c9vitez les carences nutritionnelles. Apr\u00e8s le lavage, appliquez un <strong>engrais \u00e9quilibr\u00e9<\/strong> pour reconstituer les nutriments perdus.<\/li>\n<\/ul>\n\n\n<style>\n.precios_products {\n    display: flex;\n    align-items: baseline;\n}\nspan.product_price.price_old {\n    font-size: 12px !important;\n    text-decoration: line-through;\n}\nspan.product_price.price_descuento {\n    font-size: 11px !important;\n    background: #000;\n    color: #fff;\n    padding: 0 4px;\n}\n\nspan.product_price{\n    font-family: 'Open Sans', sans-serif;\n    letter-spacing: normal !important;\n    width: fit-content !important;\n    padding: 0px 5px;\n}\n<\/style>\n<div class=\"row ppgbo_row ppgbo_product_1\">\n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/45155-medium_default\/1.jpg\"  alt=\"Flush Boom\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNTA3OS04OTUxMy1mbHVzaC1ib29tLmh0bWw=\" >Flush Boom<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(24)<\/span><\/div><div class='precios_products'><span class=\"product_price \">8,76 \u20ac<\/span><span class=\"product_price price_old\">10,95 \u20ac<\/span><span class=\"product_price price_descuento\">20%<\/span><\/div>    <\/div>\n    \n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/39395-medium_default\/1.jpg\"  alt=\"Final Flush\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNTU3LTcxNjYzLWZpbmFsLWZsdXNoLmh0bWw=\" >Final Flush<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(14)<\/span><\/div><div class='precios_products'><span class=\"product_price \">12,22 \u20ac<\/span><span class=\"product_price price_old\">16,29 \u20ac<\/span><span class=\"product_price price_descuento\">25%<\/span><\/div>    <\/div>\n    \n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/38930-medium_default\/1.jpg\"  alt=\"Flawless Finish\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNTg3LTkxNTYwLWZsYXdsZXNzLWZpbmlzaC5odG1s\" >Flawless Finish<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(12)<\/span><\/div><div class='precios_products'><span class=\"product_price \">6,78 \u20ac<\/span><span class=\"product_price price_old\">9,68 \u20ac<\/span><span class=\"product_price price_descuento\">30%<\/span><\/div>    <\/div>\n    \n    <div class=\"clear\"><\/div><\/div>\n<div class=\"clear\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Remplacez_le_substrat\"><\/span>Remplacez le substrat<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Si le substrat est fortement satur\u00e9 en chlorures, il peut \u00eatre n\u00e9cessaire de le remplacer par un nouveau. Voici comment proc\u00e9der :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Retirez d\u00e9licatement la plante.<\/strong> Retirez la plante du pot et \u00e9liminez le vieux substrat des racines.<\/li>\n\n\n\n<li>Rincez les racines <strong>avec de l&rsquo;eau propre<\/strong> pour \u00e9liminer les restes de substrat contamin\u00e9.<\/li>\n\n\n\n<li>Pr\u00e9parez le <strong>nouveau substrat.<\/strong> Utilisez un substrat de haute qualit\u00e9 avec un bon drainage.<\/li>\n\n\n\n<li><strong>Transplantez la plante<\/strong> dans le nouveau pot avec le substrat frais.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Remplacez_leau_darrosage\"><\/span>Remplacez l&rsquo;eau d&rsquo;arrosage<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Si l&rsquo;eau que vous utilisez contient des niveaux \u00e9lev\u00e9s de chlore, il est essentiel de la remplacer par une source plus appropri\u00e9e. Voici quelques alternatives :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Eau de pluie :<\/strong> une excellente option, car elle est naturellement exempte de chlore et d&rsquo;autres produits chimiques.<\/li>\n\n\n\n<li><strong>Eau repos\u00e9e :<\/strong> laissez l&rsquo;eau dans un r\u00e9cipient ouvert pendant 24 \u00e0 48 heures pour permettre au chlore de s&rsquo;\u00e9vaporer.<\/li>\n\n\n\n<li><strong>Eau filtr\u00e9e :<\/strong> utilisez un filtre \u00e0 charbon ou un <a href=\"https:\/\/www.gbthegreenbrand.fr\/traitement-des-eaux\/459-filtre-osmose-inversee-wassertech-150-190-ljour.html\">syst\u00e8me d&rsquo;osmose inverse<\/a> pour \u00e9liminer le chlore.<\/li>\n\n\n\n<li>Ajoutez du <a href=\"https:\/\/www.gbthegreenbrand.fr\/plantes-meres-et-boutures\/4744-thiosulfate-de-sodium.html\">thiosulfate de sodium<\/a>. Ce compos\u00e9 neutralise instantan\u00e9ment le chlore, mais utilisez-le avec pr\u00e9caution pour ne pas perturber l&rsquo;\u00e9quilibre de l&rsquo;eau.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ajustez_le_pH_et_lEC_du_substrat\"><\/span>Ajustez le pH et l&rsquo;EC du substrat<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Comme mentionn\u00e9 pr\u00e9c\u00e9demment, l&rsquo;exc\u00e8s de chlore peut modifier le pH et la conductivit\u00e9 \u00e9lectrique (EC) du substrat, affectant ainsi l&rsquo;absorption des nutriments. Il est donc important de <strong>corriger ces deux param\u00e8tres<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Testez le <strong>pH <\/strong>et l&rsquo;<strong>EC. <\/strong>Utilisez un <a href=\"https:\/\/www.gbthegreenbrand.fr\/controleurs-ph-ec\/4710-testeur-aquamaster-combo-p100-pro.html\">testeur de pH et d&rsquo;EC<\/a> pour \u00e9valuer l&rsquo;\u00e9tat du substrat.<\/li>\n\n\n\n<li><strong>Ajustez le pH<\/strong>. Si le pH est trop \u00e9lev\u00e9 ou trop bas, utilisez des produits sp\u00e9cifiques pour le corriger (par exemple, de l&rsquo;acide citrique pour abaisser le pH ou de la chaux pour l&rsquo;augmenter). Il est plus fr\u00e9quent de devoir acidifier le sol.<\/li>\n\n\n\n<li><strong>Surveillez l&rsquo;EC<\/strong>. Effectuez un lavage des racines si l&rsquo;EC est trop \u00e9lev\u00e9e et \u00e9vitez l&rsquo;utilisation excessive d&rsquo;engrais.<\/li>\n<\/ul>\n\n\n<style>\n.precios_products {\n    display: flex;\n    align-items: baseline;\n}\nspan.product_price.price_old {\n    font-size: 12px !important;\n    text-decoration: line-through;\n}\nspan.product_price.price_descuento {\n    font-size: 11px !important;\n    background: #000;\n    color: #fff;\n    padding: 0 4px;\n}\n\nspan.product_price{\n    font-family: 'Open Sans', sans-serif;\n    letter-spacing: normal !important;\n    width: fit-content !important;\n    padding: 0px 5px;\n}\n<\/style>\n<div class=\"row ppgbo_row ppgbo_product_1\">\n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/47973-medium_default\/1.jpg\"  alt=\"Testeur AquaMaster Combo P100 Pro pH+EC+Temp\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNDcxMC10ZXN0ZXVyLWFxdWFtYXN0ZXItY29tYm8tcDEwMC1wcm8uaHRtbA==\" >Testeur AquaMaster Combo P100 Pro pH+EC+Temp<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(5)<\/span><\/div><div class='precios_products'><span class=\"product_price \">84,11 \u20ac<\/span><span class=\"product_price price_old\">98,95 \u20ac<\/span><span class=\"product_price price_descuento\">15%<\/span><\/div>    <\/div>\n    \n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/39808-medium_default\/1.jpg\"  alt=\"Bio\u00b7Down\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNDUxOC04NTc4Ny1iaW8tZG93bi5odG1s\" >Bio\u00b7Down<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(44)<\/span><\/div><div class='precios_products'><span class=\"product_price \">5,82 \u20ac<\/span><span class=\"product_price price_old\">6,47 \u20ac<\/span><span class=\"product_price price_descuento\">10%<\/span><\/div>    <\/div>\n    \n    \n    <div class=\"product col-4\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/48034-medium_default\/1.jpg\"  alt=\"Analyseur de sol rapide NPK &amp; pH (10 tests)\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvMjY2Ni10ZXN0LXJhcGlkZS1ucGstcG91ci1zb2wtMTAtdGVzdHMuaHRtbA==\" >Analyseur de sol rapide NPK &amp; pH (10 tests)<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(4)<\/span><\/div><span class=\"product_price\">37,50 \u20ac<\/span>    <\/div>\n    \n    <div class=\"clear\"><\/div><\/div>\n<div class=\"clear\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Renforcez_les_plantes_apres_le_stress_cause_par_le_chlore\"><\/span>Renforcez les plantes apr\u00e8s le stress caus\u00e9 par le chlore<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Si les plantes ont <strong>souffert de mani\u00e8re significative<\/strong> en raison d&rsquo;un exc\u00e8s de chlore, il peut \u00eatre utile de leur apporter des compl\u00e9ments pour favoriser leur r\u00e9cup\u00e9ration.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Appliquez des <strong>mycorhizes <\/strong>et des <strong>bact\u00e9ries b\u00e9n\u00e9fiques<\/strong> pour stimuler la r\u00e9cup\u00e9ration des racines et am\u00e9liorer l&rsquo;absorption des nutriments.<\/li>\n\n\n\n<li>Utilisez des <strong>bio-stimulants<\/strong> comme des <strong>extraits d&rsquo;algues<\/strong> ou des acides amin\u00e9s, qui renforcent la r\u00e9sistance des plantes.<\/li>\n\n\n\n<li><strong>Surveillez les sympt\u00f4mes.<\/strong> Des feuilles jaunissantes, des pointes br\u00fbl\u00e9es ou une croissance lente peuvent indiquer que le chlore continue d&rsquo;affecter la plante.<\/li>\n<\/ul>\n\n\n<style>\n.precios_products {\n    display: flex;\n    align-items: baseline;\n}\nspan.product_price.price_old {\n    font-size: 12px !important;\n    text-decoration: line-through;\n}\nspan.product_price.price_descuento {\n    font-size: 11px !important;\n    background: #000;\n    color: #fff;\n    padding: 0 4px;\n}\n\nspan.product_price{\n    font-family: 'Open Sans', sans-serif;\n    letter-spacing: normal !important;\n    width: fit-content !important;\n    padding: 0px 5px;\n}\n<\/style>\n<div class=\"row ppgbo_row ppgbo_product_1\">\n    \n    <div class=\"product col-6\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/41400-medium_default\/1.jpg\"  alt=\"Soil Booster Universal\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvMTE3OS01OTk1OC1zb2lsLWJvb3N0ZXItdW5pdmVyc2FsLmh0bWw=\" >Soil Booster Universal<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(18)<\/span><\/div><div class='precios_products'><span class=\"product_price \">21,31 \u20ac<\/span><span class=\"product_price price_old\">28,41 \u20ac<\/span><span class=\"product_price price_descuento\">25%<\/span><\/div>    <\/div>\n    \n    \n    <div class=\"product col-6\">\n        <img loading=\"lazy\" decoding=\"async\" class=\"product_image\" src=\"https:\/\/www.growbarato.net\/38862-medium_default\/1.jpg\"  alt=\"Roots GB Nutrients\" width=\"250\" height=\"250\" \/><h4 style=\"cursor:pointer\" class=\"ppgbo_qcd product_name clickproducttitleblog\" data-tab=\"_blank\" data-qcd=\"aHR0cHM6Ly93d3cuZ3Jvd2JhcmF0by5uZXQvZnIvNzY1MC0xMDE2OTYtcm9vdHMtZ2ItbnV0cmllbnRzLmh0bWw=\" >Roots GB Nutrients<\/h4><div class='estrellas' style='display: flex;align-items: center;'><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><div class=\"star\"><i class=\"fas fa-star\"><\/i><\/div><span style='font-size:14px; margin-left:5px;'>(4)<\/span><\/div><span class=\"product_price\">5,00 \u20ac<\/span>    <\/div>\n    \n    <\/div>\n<div class=\"clear\"><\/div>\n\n\n\n<p>En r\u00e9sum\u00e9, l&rsquo;<strong>exc\u00e8s de chlore dans les plantes<\/strong>, en particulier dans la culture du cannabis, est un probl\u00e8me qu&rsquo;il ne faut pas sous-estimer. Il est important de le d\u00e9tecter rapidement et d&rsquo;appliquer les solutions appropri\u00e9es pour maintenir la sant\u00e9 et le rendement de vos plantes. L&rsquo;eau du robinet que nous utilisons souvent contient souvent des niveaux de chlore qui peuvent \u00eatre nocifs pour de nombreuses plantes. C&rsquo;est pourquoi il est pr\u00e9f\u00e9rable de mettre en place une s\u00e9rie de <strong>mesures pr\u00e9ventives<\/strong> pour \u00e9viter d&rsquo;\u00e9ventuels dommages. Si vous souhaitez en savoir plus sur l&rsquo;entretien de vos plantes de cannabis, ne manquez pas les prochains articles du blog.<\/p>\n\n\n\n<style>\n    .accordion-container {\n      width: 100%;\n      margin: 0 0 20px;\n      clear:both;\n    }\n    h3.accordion-titulo {\n        margin-bottom: 0;\n        margin-top: 2%;\n    }\n    .accordion-titulo {\n      position: relative;\n      display: block;\n      padding: 10px 20px;\n      font-size: 18px;\n      font-weight: 300;\n      border: 1px solid #000;\n      color: #000;\n      text-decoration: none;\n      cursor: pointer;\n    }\n    .accordion-titulo.open {\n      color: #00ab8e;\n      border-color: #00ab8e;\n    }\n    .accordion-titulo:hover {\n      color: #00ab8e;\n      border-color: #00ab8e;\n    }\n    .accordion-titulo span.toggle-icon:before {\n      content:\"+\";\n    }\n    .accordion-titulo.open span.toggle-icon:before {\n      content:\"-\";\n    }\n    .accordion-titulo span.toggle-icon {\n      position: absolute;\n      top: 6px;\n      right: 20px;\n      font-size: 26px;\n      font-weight:bold;\n    }\n    .accordion-content {\n      display: none;\n      padding: 20px;\n      overflow: auto;\n      font-family: 'Roboto', sans-serif;\n      font-size: 16px;\n    }\n    @media (max-width: 767px) {\n       h3.accordion-titulo {\n        padding-right: 12%;\n       }\n    }\n<\/style>\n\n<script>\n    jQuery( document ).ready(function($) {\n      $(\".accordion-titulo\").click(function(){\n\n        var contenido = $(this).next(\".accordion-content\");\n          \n        if(contenido.css(\"display\")==\"none\") { \/\/open        \n          contenido.slideDown(250);            \n          $(this).addClass(\"open\");\n        }\n        else { \/\/close        \n          contenido.slideUp(250);\n          $(this).removeClass(\"open\");    \n        }\n                  \n      });\n    });\n<\/script>\n\n<div itemscope=\"\" itemtype=\"https:\/\/schema.org\/FAQPage\" style=\"width: 80%; max-width: 100%\">\n    <h2 style=\"width: 100% !important;\"><span class=\"ez-toc-section\" id=\"FAQ_sur_lexces_de_chlore_dans_les_plantes\"><\/span>FAQ sur l&rsquo;exc\u00e8s de chlore dans les plantes<span class=\"ez-toc-section-end\"><\/span><\/h2>  \n    <div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n        <h3 itemprop=\"name\" class=\"accordion-titulo\" style=\"width: 100% !important;\"><span class=\"ez-toc-section\" id=\"Comment_savoir_si_ma_plante_a_un_exces_de_chlore\"><\/span>Comment savoir si ma plante a un exc\u00e8s de chlore ?\n          <span class=\"toggle-icon\"><\/span> <span class=\"ez-toc-section-end\"><\/span><\/h3>\n        <div class=\"accordion-content\" itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n            <div itemprop=\"text\">\n                Les feuilles peuvent pr\u00e9senter des pointes br\u00fbl\u00e9es, des bords jaunes ou bruns et une croissance lente. Le sol peut \u00e9galement avoir une couche blanche \u00e0 la surface.\n            <\/div>\n        <\/div>\n    <\/div>\n    <div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n        <h3 itemprop=\"name\" class=\"accordion-titulo\" style=\"width: 100% !important;\"><span class=\"ez-toc-section\" id=\"Leau_du_robinet_peut-elle_provoquer_un_exces_de_chlore_dans_les_plantes\"><\/span>L&rsquo;eau du robinet peut-elle provoquer un exc\u00e8s de chlore dans les plantes ?\n            <span class=\"toggle-icon\"><\/span>\n        <span class=\"ez-toc-section-end\"><\/span><\/h3>\n        <div class=\"accordion-content\" itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n            <div itemprop=\"text\">\n               Oui, l&rsquo;eau du robinet contient souvent du chlore qui, en exc\u00e8s, peut endommager les plantes, surtout si elle n&rsquo;est pas laiss\u00e9e \u00e0 reposer avant utilisation.\n            <\/div>\n        <\/div>\n    <\/div>\n    \n    <div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n        <h3 itemprop=\"name\" class=\"accordion-titulo\" style=\"width: 100% !important;\"><span class=\"ez-toc-section\" id=\"Que_faire_si_ma_plante_a_deja_un_exces_de_chlore\"><\/span>Que faire si ma plante a d\u00e9j\u00e0 un exc\u00e8s de chlore ?\n            <span class=\"toggle-icon\"><\/span>\n        <span class=\"ez-toc-section-end\"><\/span><\/h3>\n        <div class=\"accordion-content\" itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n            <div itemprop=\"text\">\n              Rincez le sol avec de l&rsquo;eau sans chlore pour \u00e9liminer l&rsquo;exc\u00e8s et rempotez la plante dans un substrat frais si n\u00e9cessaire.\n            <\/div>\n        <\/div>\n    <\/div>\n    <div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n        <h3 itemprop=\"name\" class=\"accordion-titulo\" style=\"width: 100% !important;\"><span class=\"ez-toc-section\" id=\"Un_exces_de_chlore_peut-il_tuer_une_plante\"><\/span>Un exc\u00e8s de chlore peut-il tuer une plante ?\n            <span class=\"toggle-icon\"><\/span>\n        <span class=\"ez-toc-section-end\"><\/span><\/h3>\n        <div class=\"accordion-content\" itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n            <div itemprop=\"text\">\n               Dans les cas extr\u00eames, oui, un exc\u00e8s de chlore peut endommager les racines et affecter l&rsquo;absorption des nutriments, ce qui peut entra\u00eener la mort de la plante.\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Le chlore est un \u00e9l\u00e9ment essentiel pour la croissance des plantes, mais en exc\u00e8s, il peut devenir un ennemi silencieux. D\u00e9couvrez comment identifier l&rsquo;effet du chlore sur les plantes en cas d&rsquo;application excessive, ainsi que les solutions pratiques pour le corriger et le pr\u00e9venir. Nous vous donnerons \u00e9galement des conseils sur la fa\u00e7on de choisir\u2026 <span class=\"leermas\" onclick=\"window.location.href='https:\/\/www.gbthegreenbrand.fr\/blog\/effet-du-chlore-sur-les-plantes-avantages-et-risques-dexces\/'\">Lire la suite<\/span ><\/p>\n","protected":false},"author":18,"featured_media":199936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"BlogPosting","footnotes":""},"categories":[264,263],"tags":[],"class_list":{"0":"post-203412","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guide-de-culture","8":"category-conseils"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":10,"sum_votes":48},"_links":{"self":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/203412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/comments?post=203412"}],"version-history":[{"count":14,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/203412\/revisions"}],"predecessor-version":[{"id":217194,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/203412\/revisions\/217194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media\/199936"}],"wp:attachment":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media?parent=203412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/categories?post=203412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/tags?post=203412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}