{"id":86753,"date":"2022-05-09T00:00:00","date_gmt":"2022-05-08T22:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/"},"modified":"2023-04-14T11:47:56","modified_gmt":"2023-04-14T09:47:56","slug":"quels-types-de-graines-de-cannabis-existe-t-il","status":"publish","type":"post","link":"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/","title":{"rendered":"Quels types de graines de cannabis existe-t-il ?"},"content":{"rendered":"\n<p>D\u00e8s les ann\u00e9es 90 \u00e0 nos jours, la <strong>vari\u00e9t\u00e9 de types de graines de cannabis a \u00e9norm\u00e9ment chang\u00e9<\/strong>. Ant\u00e9rieurement, les cultivateurs ne pouvaient que choisir parmi des souches indica, sativa ou hybrides r\u00e9guli\u00e8res. Les banques de graines conjointement aux breeders, ont r\u00e9alis\u00e9 un fantastique travail de recherche et de cr\u00e9ation. Celui-ci, a donn\u00e9 lieu \u00e0 une offre impressionnante qui s&rsquo;adapte \u00e0 tout type de cultivateur ou amateur de cannabis.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a9861c454f13\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9861c454f13\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Types_de_graines_de_cannabis\" >Types de graines de cannabis<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_indica\" >Graines indica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_Sativa\" >Graines Sativa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_hybrides\" >Graines hybrides<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_Ruderalis\" >Graines Ruderalis<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Autres_types_de_graines_de_cannabis\" >Autres types de graines de cannabis<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_regulieres\" >Graines r\u00e9guli\u00e8res<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_feminisees\" >Graines f\u00e9minis\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_autofloraison\" >Graines autofloraison<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_de_CBD\" >Graines de CBD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_de_chanvre\" >Graines de chanvre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/#Graines_Fast_Version\" >Graines Fast Version<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Types_de_graines_de_cannabis\"><\/span>Types de graines de cannabis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_indica\"><\/span>Graines indica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ce type de graine <strong>se caract\u00e9rise par sa fantastique relation production\/cycle de vie<\/strong>. G\u00e9n\u00e9ralement, elles sont plus productives que les sativa, et le temps de d\u00e9veloppement est plus court. La diff\u00e9rence quant aux rendements, \u00e9tant les indica les <a href=\"https:\/\/www.gbthegreenbrand.fr\/224-graines-de-cannabis\">graines de cannabis<\/a> plus productives, est d\u00fb \u00e0 la densit\u00e9 de leurs bourgeons ; cependant, ceci les rend moins r\u00e9sistantes face aux moisissures, surtout dans des zones humides et chaudes.<\/p>\n\n\n\n<p>Il est possible de diff\u00e9rencier les diff\u00e9rentes vari\u00e9t\u00e9s gr\u00e2ce aux caract\u00e9ristiques que chacune refl\u00e8te lors de sa croissance. Les graines indica poussent en forme de sapin de No\u00ebl. En vue d\u2019un accroissement des productions finales, il est souhaitable de r\u00e9aliser une <strong>taille apicale ou bien la <\/strong><a href=\"https:\/\/www.gbthegreenbrand.fr\/blog\/lst-low-stress-training-technique-de-culture-de-cannabis\/\">technique LST<\/a>, et permettre \u00e0 la lumi\u00e8re d\u2019atteindre toute la plante. Les tonalit\u00e9s vert fonc\u00e9, de m\u00eame que la forme ample de leurs feuilles, sont aussi propres des indica.<\/p>\n\n\n\n<p>En raison de sa taille mod\u00e9r\u00e9e, ce type <strong>est id\u00e9al pour cultiver en int\u00e9rieur<\/strong> ou dans des espaces r\u00e9duit. Leur courte phase g\u00e9n\u00e9rative, rend ce type de graine, convenables pour l\u2019ext\u00e9rieur puisqu&rsquo;elles seront pr\u00eates avant les premi\u00e8res gel\u00e9es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_Sativa\"><\/span>Graines Sativa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Le cannabis sativa offre une moindre production, alors si vous souhaitez g\u00e9n\u00e9rer la m\u00eame quantit\u00e9, il faut plus de plantes. Toutefois, les <strong>bourgeons sont plus a\u00e9r\u00e9s et spongieux,<\/strong> et par cons\u00e9quent plus r\u00e9sistants \u00e0 l&rsquo;humidit\u00e9 et autres. En outre, le THC de ce type de vari\u00e9t\u00e9 est sup\u00e9rieur et leurs effets plus \u00e9nergisants ainsi que c\u00e9r\u00e9braux ; en plus, elles affichent des saveurs exotiques et tropicales. Pour cette raison, les graines sativa sont les plus recherch\u00e9es par les cultivateurs.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/Hoja-marihuana-sativa.jpg.webp\" alt=\"feuille graine de cannabis sativa\n\" class=\"wp-image-51254\" title=\"Types de graines de cannabis sativa\"\/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Comme pour les fleurs, les plantes se d\u00e9veloppent a\u00e9r\u00e9es et allong\u00e9es. Les follicules des feuilles pr\u00e9sentent plus de distance et les tons verts clairs. D\u00fb \u00e0 sa grande taille et \u00e0 l&rsquo;espace qu\u2019elle exige pour bien pousser, si vous souhaitez les cultiver indoor ou dans des balcons, cela implique r\u00e9aliser des techniques qui modifient leur verticalit\u00e9 par une croissance horizontale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_hybrides\"><\/span>Graines hybrides<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les hybrides naissent du <strong>croisement entre deux types de g\u00e9n\u00e9tiques, <\/strong>notamment une indica et une sativa. En effet, l&rsquo;intention est de cr\u00e9er des graines exhibant des propri\u00e9t\u00e9s meilleures. En effet, le but de l\u2019hybridation est de r\u00e9duire le temps de floraison d\u2019une sativa, d\u2019apporter des go\u00fbts exotiques aux souches classiques indica ou bien d\u2019obtenir une productivit\u00e9 majeure d\u2019une sativa tout en rendant ses fleurs plus denses et compactes.<\/p>\n\n\n\n<p>Les banques r\u00e9alisent souvent l&rsquo;hybridation en vue de produire de nouvelles vari\u00e9t\u00e9s de sorte \u00e0 offrir les meilleures plantes \u00e0 leurs clients. Lorsque l\u2019on croise deux vari\u00e9t\u00e9s, il y a des ph\u00e9notypes qui apparaissent. Ce sont des exemplaires avec des caract\u00e9ristiques vari\u00e9es mais une m\u00eame g\u00e9n\u00e9tique. Les banques s\u00e9lectionnent celles qui se ressemblent le plus, afin de les stabiliser et d\u2019offrir sa meilleure version.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_Ruderalis\"><\/span>Graines Ruderalis<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les graines ruderalis sont les moins connues, car quasiment aucune banque ne les commercialise. On les utilise uniquement pour r\u00e9aliser des hybridations car <strong>leurs g\u00e8nes rendent autoflorissante toute vari\u00e9t\u00e9<\/strong> avec laquelle elles sont crois\u00e9es.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/planta-al-atardecer.jpg.webp\" alt=\"Plante de cannabis ruderalis\" class=\"wp-image-51255\" width=\"600\" height=\"453\" title=\"types de graines ruderalis\"\/><\/figure><\/div>\n\n\n\n<p>Le cannabis ruderalis est une plante sauvage qui provient des zones les plus froides du nord d\u2019Europe, la Russie centrale et la Sib\u00e9rie. La faible quantit\u00e9 de lumi\u00e8re re\u00e7ue et les gel\u00e9s ont oblig\u00e9 \u00e0 ce type de graine de cannabis \u00e0 s\u2019adapter \u00e0 cet environnement et \u00e0 <strong>fleurir sans changement de lumi\u00e8re et sous de conditions extr\u00eames.<\/strong><\/p>\n\n\n\n<p>En outre, elles offrent des <strong>taux de THC inf\u00e9rieurs \u00e0 3 %<\/strong> et ne grandissent presque pas par rapport au reste de vari\u00e9t\u00e9s. Compactes et robustes, deux adjectifs qui d\u00e9crivent les plantes de ce type de graine. Elles d\u00e9veloppent des fleurs petites mais grosses ; n\u00e9anmoins, sa faible concentration de THC et de CBD, n&rsquo;int\u00e9resse pas les commer\u00e7ants pour l&#8217;employer au-del\u00e0 des croisements pour obtenir des souches \u00e0 autofloraison.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Autres_types_de_graines_de_cannabis\"><\/span>Autres types de graines de cannabis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Outre les types de cannabis qui existe en fonction de la graine de cannabis dont elle provient, celui-ci peut \u00eatre aussi classifi\u00e9 d\u2019autres mani\u00e8res : par sa d\u00e9pendance aux photop\u00e9riodes, par sexe ou par taux de THC et CBD.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_regulieres\"><\/span>Graines r\u00e9guli\u00e8res<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les r\u00e9guli\u00e8res furent les premi\u00e8res utilis\u00e9es pour la culture de cannabis. En effet, elles sont <strong>capables de germer tant dans les plantes m\u00e2les que les femelles<\/strong>. Ceci suppose un probl\u00e8me pour les personnes qui souhaitent une grande quantit\u00e9 de fleurs dans leurs cultures ; ce type de graine de cannabis germait dans un 90 % des m\u00e2les.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/planta-de-marihuana-en-principios-de-floracion.jpg.webp\" alt=\"Plante de type de graine de cannabis r\u00e9guli\u00e8re\" class=\"wp-image-51256\" title=\"Plante r\u00e9guli\u00e8re de cannabis\"\/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Les m\u00e2les produisent le pollen n\u00e9cessaire aux femelles pour cr\u00e9er des types de graines. Elles peuvent se cultiver pour g\u00e9n\u00e9rer de nouvelles plantes, mais elles produisent aussi des fleurs. Une femelle pollinis\u00e9e signifie une production pauvre, pleine de graines et de mauvaise qualit\u00e9. Pour cette raison, il \u00e9tait n\u00e9cessaire de se d\u00e9barrasser des plantes m\u00e2les une fois qu&rsquo;elles avaient \u00e9t\u00e9 identifi\u00e9es. Aujourd&rsquo;hui, l&rsquo;utilisation de ce type de cannabis a \u00e9t\u00e9 r\u00e9duite aux <strong>cultivateurs <\/strong>ou aux banques <strong>qui produisent leurs propres hybrides<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_feminisees\"><\/span>Graines f\u00e9minis\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les <a href=\"https:\/\/www.gbthegreenbrand.fr\/40-graines-feminisees\">f\u00e9minis\u00e9es <\/a>ont \u00e9t\u00e9 modifi\u00e9es de mani\u00e8re \u00e0 ce qu&rsquo;elles soient <strong>incapables de cr\u00e9er des chromosomes m\u00e2les<\/strong>. Elles font pousser en permanence des plantes femelles qui produisent les pr\u00e9cieuses fleurs. La f\u00e9minisation de n&rsquo;importe quel type de graine de cannabis conventionnelle est une t\u00e2che ardue qui n\u00e9cessite beaucoup de tests et de temps pour garantir la stabilit\u00e9 et la coh\u00e9rence, et afin de les commercialiser sous le nom de f\u00e9minis\u00e9es.<\/p>\n\n\n\n<p>Ce processus est <strong>efficace \u00e0 99,9 %<\/strong>, il y aura donc toujours une petite chance de faire germer une plante m\u00e2le. Cependant, tout type de graine de cannabis f\u00e9minis\u00e9e est un meilleur choix qu&rsquo;une graine r\u00e9guli\u00e8re pour les cultivateurs traditionnels. Ils \u00e9vitent de devoir diff\u00e9rencier le sexe des plantes et d&rsquo;\u00eatre en alerte constante pour \u00e9liminer les m\u00e2les \u00e0 temps. En outre, ils assurent la production de bourgeons \u00e0 la fin de la r\u00e9colte dans le cadre de soins rudimentaires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_autofloraison\"><\/span>Graines autofloraison<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les autofloraison <strong>changent de phase ind\u00e9pendamment des caract\u00e9ristiques environnementales<\/strong> qui les entourent. Elles sont auto-programm\u00e9es pour entrer dans la phase g\u00e9n\u00e9rative apr\u00e8s quelques semaines de croissance. Elles sont tr\u00e8s faciles \u00e0 cultiver car ce type de plante de cannabis peut se d\u00e9velopper m\u00eame avec seulement quelques heures de lumi\u00e8re par jour. En fait, elles pr\u00e9sentent une grande tol\u00e9rance \u00e0 la pollution lumineuse, de sorte que l&rsquo;interruption de leurs heures d&rsquo;obscurit\u00e9 ne les affecte pas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/cogollo-de-marihuana-rosa.jpg-1.webp\" alt=\"Fleur de cannabis autofloraison\" class=\"wp-image-51258\" title=\"Plante de cannabis autofloraison\"\/><\/figure><\/div>\n\n\n\n<p>Ce type de graine de cannabis est le plus recommand\u00e9 pour commencer \u00e0 prendre de l\u2019exp\u00e9rience en cultivant ou pour les personnes qui ne disposent pas de trop de temps pour le d\u00e9dier aux plantes. Forc\u00e9ment, plus les soins sont minutieux, plus la productivit\u00e9 sera am\u00e9lior\u00e9e.<\/p>\n\n\n\n<p>Les souches \u00e0 autofloraison sont cr\u00e9\u00e9es en <strong>m\u00e9langeant une graine f\u00e9minis\u00e9e ou r\u00e9guli\u00e8re avec une ruderalis<\/strong>. De cette derni\u00e8re, elle h\u00e9rite sa courte floraison, une croissance plus faible, sa r\u00e9sistance et sa capacit\u00e9 de fleurir sous tout type de conditions. Ce type de plantes sera pr\u00eat pour la coupe apr\u00e8s 10 &#8211; 12 semaines d\u00e8s la germination. Bien que sa production soit inf\u00e9rieure \u00e0 celle d\u2019une femelle, vous pourrez r\u00e9aliser plus de cultures dans une m\u00eame ann\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_de_CBD\"><\/span>Graines de CBD<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Tous les types de graines de cannabis de CBD, pr\u00e9sentent les caract\u00e9ristiques des graines f\u00e9minis\u00e9es, r\u00e9guli\u00e8res ou automatiques affichant un <strong>taux de CBD plus \u00e9lev\u00e9 que d\u2019habitude<\/strong>. De plus, dans beaucoup de cas, ils essayent de diminuer les taux de THC le maximum possible pour les utiliser \u00e0 des fins th\u00e9rapeutiques.<\/p>\n\n\n\n<p><br>Nonobstant, ces graines ne contiennent jamais le taux ad\u00e9quat de THC pour pouvoir \u00eatre utilis\u00e9es dans la fabrication de produits l\u00e9gaux de CBD, qui est de 0,2 %. Dans cette optique, les graines de chanvre sont plus fr\u00e9quentes. En outre, ce type de graine de cannabis compte avec <strong>des effets plus relaxants et anti-stress<\/strong> que le reste.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_de_chanvre\"><\/span>Graines de chanvre<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Contrairement aux graines de CBD, celles-ci <strong>contiennent des taux de THC inf\u00e9rieurs \u00e0 0,2 %<\/strong>, donc c\u2019est le <strong>CBD qui pr\u00e9domine<\/strong>. \u00c9galement connue sous le nom de chanvre industriel, elle s&#8217;emploie pour extraire le CBD et cr\u00e9er des produits \u00e0 des fins th\u00e9rapeutiques.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/semillas-de-CBD-y-canamo.jpg.webp\" alt=\"Graines de chanvre\" class=\"wp-image-51259\" title=\"Graines de cannabis de chanvre\"\/><\/figure><\/div>\n\n\n\n<p>Les graines de chanvre ne s\u2019utilisent pas uniquement pour obtenir le cannabidiol. Elle offre des fibres hautement r\u00e9sistantes pour <strong>l&rsquo;industrie textile, pour produire du papier, comme \u00e9l\u00e9ment isolant, pour la fabrication de cordes<\/strong>, combustible pour le moteur, peintures, cosm\u00e9tiques, etc. Par ailleurs, leurs graines peuvent se consommer sous forme d&rsquo; huile, crues, enti\u00e8res, toast\u00e9s ou transform\u00e9es en farine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Graines_Fast_Version\"><\/span>Graines Fast Version<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Comme pour les graines de cannabis CBD, ces types de graines de cannabis poss\u00e8dent quasi les caract\u00e9ristiques d\u2019une r\u00e9guli\u00e8re ou f\u00e9minis\u00e9e, mais son<strong> cycle de vie est plus court<\/strong> que d\u2019habitude pour r\u00e9colter avant les premi\u00e8res gel\u00e9es d\u2019octobre. En effet, de <strong>nombreuses graines se compl\u00e8tent<\/strong>. Les souches sativa, indica, hybrides ou ruderalis peuvent \u00eatre f\u00e9minis\u00e9es, r\u00e9guli\u00e8res, autofleurissantes ou bien Fast Version. Finalement, les graines de chanvre sont toutes sativa.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>D\u00e8s les ann\u00e9es 90 \u00e0 nos jours, la vari\u00e9t\u00e9 de types de graines de cannabis a \u00e9norm\u00e9ment chang\u00e9. Ant\u00e9rieurement, les cultivateurs ne pouvaient que choisir parmi des souches indica, sativa ou hybrides r\u00e9guli\u00e8res. Les banques de graines conjointement aux breeders, ont r\u00e9alis\u00e9 un fantastique travail de recherche et de cr\u00e9ation. Celui-ci, a donn\u00e9 lieu \u00e0\u2026 <span class=\"leermas\" onclick=\"window.location.href='https:\/\/www.gbthegreenbrand.fr\/blog\/quels-types-de-graines-de-cannabis-existe-t-il\/'\">Lire la suite<\/span ><\/p>\n","protected":false},"author":18,"featured_media":171062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[225],"tags":[],"class_list":{"0":"post-86753","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites-sur-le-cannabis"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":5},"_links":{"self":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/86753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/comments?post=86753"}],"version-history":[{"count":10,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/86753\/revisions"}],"predecessor-version":[{"id":120654,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/posts\/86753\/revisions\/120654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media\/171062"}],"wp:attachment":[{"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/media?parent=86753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/categories?post=86753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.fr\/blog\/wp-json\/wp\/v2\/tags?post=86753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}